{"id":13222,"date":"2018-10-10T23:35:39","date_gmt":"2018-10-10T21:35:39","guid":{"rendered":"http:\/\/orthodoxia.be\/?p=13222"},"modified":"2018-10-18T13:03:17","modified_gmt":"2018-10-18T11:03:17","slug":"ouverture-de-lannee-academique-a-linstitut-de-theologie-orthodoxe-apotre-paul-et-du-cycle-de-conferences-orthodoxos-logos-a-bruxelles","status":"publish","type":"post","link":"https:\/\/orthodoxia.be\/fr\/2018\/10\/10\/ouverture-de-lannee-academique-a-linstitut-de-theologie-orthodoxe-apotre-paul-et-du-cycle-de-conferences-orthodoxos-logos-a-bruxelles\/","title":{"rendered":"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles"},"content":{"rendered":"<p style=\"text-align: justify;\">L\u2019Archev\u00each\u00e9 Orthodoxe de Belgique a proc\u00e9d\u00e9, mercredi 10 octobre 2018, \u00e0 l\u2019ouverture de l\u2019Ann\u00e9e Acad\u00e9mique 2018-2019 de l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles, dans la salle de conf\u00e9rence du Couvent des Dominicains, en plein centre de la ville de Bruxelles.<\/p>\n<p style=\"text-align: justify;\">La rencontre d\u00e9buta par une c\u00e9r\u00e9monie pour l\u2019ouverture de la nouvelle ann\u00e9e acad\u00e9mique avec Son \u00c9minence le M\u00e9tropolite Ath\u00e9nagoras de Belgique b\u00e9nissant aussi bien le d\u00e9but des cours de l\u2019Institut que celui du nouveau Cycle de Conf\u00e9rences. Prenant ensuite la parole, il devait remercier les personnes pr\u00e9sentes et se r\u00e9f\u00e9rer \u00e0 l\u2019histoire et \u00e0 l\u2019actif de l\u2019Institut.<\/p>\n<p style=\"text-align: justify;\">L\u2019Archev\u00each\u00e9 Orthodoxe de Belgique et son responsable, le M\u00e9tropolite du Patriarcat \u0152cum\u00e9nique, dans le cadre de ses pr\u00e9rogatives et obligations impos\u00e9es par l\u2019\u00c9tat belge, a la possibilit\u00e9 de d\u00e9signer des enseignants pour le cours de religion orthodoxe dans les \u00e9coles de l\u2019Enseignement officiel. Ce privil\u00e8ge a amen\u00e9 la n\u00e9cessit\u00e9 de fonder un Institut en mesure d\u2019informer et de former les candidats enseignants du cours, mais aussi des membres du clerg\u00e9 et des cat\u00e9chistes. L\u2019Institut est en fonction depuis 1991, avec deux sections\u00a0: \u00e0 Gand pour les besoins des n\u00e9erlandophones et \u00e0 Bruxelles pour les francophones.<\/p>\n<p style=\"text-align: justify;\">Sous l\u2019inspiration de l\u2019ex-M\u00e9tropolite Panteleimon de Belgique, mais aussi avec le soutien et les conseils de l\u2019\u00c9v\u00eaque \u00e0 cette \u00e9poque Ath\u00e9nagoras de Sinope, aujourd\u2019hui actuel M\u00e9tropolite de Belgique, des enseignants sont d\u00e9sign\u00e9s, avec la possibilit\u00e9 de se former dans une des deux sections de l\u2019Institut de mani\u00e8re \u00e0 \u00eatre en mesure de mener \u00e0 bien l\u2019enseignement du cours de religion dans les cycles de l\u2019Enseignement officiel.<\/p>\n<p style=\"text-align: justify;\">Il est \u00e0 noter que le cours de religion dans l\u2019Enseignement officiel en Belgique est une option obligatoire, laiss\u00e9e librement au choix de chaque parent. Le choix d\u2019un seul \u00e9l\u00e8ve dans une classe pour le cours de religion orthodoxe oblige la direction de l\u2019\u00e9cole ou le Pouvoir Organisateur de l\u2019Institution scolaire de s\u2019adresser \u00e0 l\u2019Archev\u00each\u00e9 qui se doit de d\u00e9signer un enseignant pour les besoins du cours.<\/p>\n<p style=\"text-align: justify;\">Le M\u00e9tropolite Ath\u00e9nagoras souligna d\u00e8s lors l\u2019importance de l\u2019existence et du fonctionnement de l\u2019Institut de Th\u00e9ologie Orthodoxe en Belgique, non seulement pour r\u00e9pondre aux besoins du cursus, mais aussi pour le d\u00e9veloppement de la pens\u00e9e et tradition Orthodoxe au c\u0153ur de l\u2019Europe.<\/p>\n<p style=\"text-align: justify;\">Ensuite, le Directeur de l\u2019Institut Ap\u00f4tre Paul, l\u2019Archipr\u00eatre Dr Constantin Kenanidis, pr\u00e9senta le nouveau programme des cours, ainsi que le staff des professeurs, th\u00e9ologiens aguerris, pr\u00eatres des divers pr\u00e9sences Orthodoxes et la\u00efcs qui veillent \u00e0 couvrir tous les pans d\u2019une pr\u00e9paration ad\u00e9quate des futurs enseignants, sans oublier \u00e9galement la formation de tous ceux qui montrent de l\u2019int\u00e9r\u00eat pour la Th\u00e9ologie orthodoxe.<\/p>\n<p style=\"text-align: justify;\">Dans la deuxi\u00e8me partie de la soir\u00e9e, eut lieu la premi\u00e8re conf\u00e9rence du Cycle \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb de l\u2019Archev\u00each\u00e9, avec comme invit\u00e9 le professeur de Th\u00e9ologie et r\u00e9put\u00e9 \u00e9crivain fran\u00e7ais, Dr. Jean-Claude Larchet qui d\u00e9veloppa le sujet\u00a0: \u00ab\u00a0Comment garder et transmettre la Foi chr\u00e9tienne dans un monde qui se d\u00e9christianise\u00a0?\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Le r\u00e9put\u00e9 th\u00e9ologien d\u00e9veloppa dans un premier temps les nombreuses difficult\u00e9s rencontr\u00e9es dans notre soci\u00e9t\u00e9 d\u00e9christianis\u00e9e qui continue \u00e0 s\u2019\u00e9loigner de Dieu et de la Foi. Dans une Europe \u00e0 l\u2019identit\u00e9 chr\u00e9tienne et dont la base de sa culture est le christianisme, le d\u00e9mant\u00e8lement de la Foi provoque des secousses dans ses fondements. En cons\u00e9quence, il proposa des solutions et des r\u00e9ponses sur ce que pourraient offrir les chr\u00e9tiens qui en ont conscience pour ramener le christianisme dans le quotidien en tant que part importante, non seulement de la vie, mais de notre identit\u00e9 d\u2019Europ\u00e9en.<br \/>\nCoordinateur du Cycle de Conf\u00e9rences\u00a0: l\u2019Archidiacre Philadelphos Kafalis, directeur du Bureau Particulier du M\u00e9tropolite.<\/p>\n<p style=\"text-align: justify;\">La conf\u00e9rence fut suivie d\u2019une r\u00e9ception.<\/p>\n<p>[FAGP id=13164]<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/09\/Larchet-FR_V3-sm.jpg\" alt=\"\" width=\"100%\" class=\"alignnone size-full wp-image-12407\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Archev\u00each\u00e9 Orthodoxe de Belgique a proc\u00e9d\u00e9, mercredi 10 octobre 2018, \u00e0 l\u2019ouverture de l\u2019Ann\u00e9e Acad\u00e9mique 2018-2019 de l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles, dans la salle de conf\u00e9rence du Couvent des Dominicains, en plein centre de la ville de Bruxelles. La rencontre d\u00e9buta par une c\u00e9r\u00e9monie &hellip; <a href=\"https:\/\/orthodoxia.be\/fr\/2018\/10\/10\/ouverture-de-lannee-academique-a-linstitut-de-theologie-orthodoxe-apotre-paul-et-du-cycle-de-conferences-orthodoxos-logos-a-bruxelles\/\">Continued<\/a><\/p>\n","protected":false},"author":2,"featured_media":13170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,36],"tags":[],"class_list":["post-13222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-orthodox-logos-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles - Archev\u00each\u00e9 Orthodoxe de Belgique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orthodoxia.be\/2018\/10\/10\/\u03ad\u03bd\u03b1\u03c1\u03be\u03b7-\u03c4\u03bf\u03c5-\u03b1\u03ba\u03b1\u03b4\u03b7\u03bc\u03b1\u03ca\u03ba\u03bf\u03cd-\u03ad\u03c4\u03bf\u03c5\u03c2-\u03b9\u03bd\u03c3\u03c4\u03b9\u03c4\u03bf\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles - Archev\u00each\u00e9 Orthodoxe de Belgique\" \/>\n<meta property=\"og:description\" content=\"L\u2019Archev\u00each\u00e9 Orthodoxe de Belgique a proc\u00e9d\u00e9, mercredi 10 octobre 2018, \u00e0 l\u2019ouverture de l\u2019Ann\u00e9e Acad\u00e9mique 2018-2019 de l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles, dans la salle de conf\u00e9rence du Couvent des Dominicains, en plein centre de la ville de Bruxelles. La rencontre d\u00e9buta par une c\u00e9r\u00e9monie &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orthodoxia.be\/2018\/10\/10\/\u03ad\u03bd\u03b1\u03c1\u03be\u03b7-\u03c4\u03bf\u03c5-\u03b1\u03ba\u03b1\u03b4\u03b7\u03bc\u03b1\u03ca\u03ba\u03bf\u03cd-\u03ad\u03c4\u03bf\u03c5\u03c2-\u03b9\u03bd\u03c3\u03c4\u03b9\u03c4\u03bf\/\" \/>\n<meta property=\"og:site_name\" content=\"Archev\u00each\u00e9 Orthodoxe de Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/orthobel\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-10T21:35:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-18T11:03:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Georgios Tzatzanis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@orthobel\" \/>\n<meta name=\"twitter:site\" content=\"@orthobel\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Georgios Tzatzanis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/\"},\"author\":{\"name\":\"Georgios Tzatzanis\",\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/person\/36bdc09a0ba8f97671645b7e9d8533ee\"},\"headline\":\"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles\",\"datePublished\":\"2018-10-10T21:35:39+00:00\",\"dateModified\":\"2018-10-18T11:03:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/\"},\"wordCount\":744,\"publisher\":{\"@id\":\"https:\/\/orthodoxia.be\/#organization\"},\"image\":{\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg\",\"articleSection\":[\"Actualit\u00e9\",\"Orthodox Logos\"],\"inLanguage\":\"fr-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/\",\"url\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/\",\"name\":\"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles - Archev\u00each\u00e9 Orthodoxe de Belgique\",\"isPartOf\":{\"@id\":\"https:\/\/orthodoxia.be\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg\",\"datePublished\":\"2018-10-10T21:35:39+00:00\",\"dateModified\":\"2018-10-18T11:03:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#primaryimage\",\"url\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg\",\"contentUrl\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg\",\"width\":1200,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/orthodoxia.be\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/orthodoxia.be\/#website\",\"url\":\"https:\/\/orthodoxia.be\/\",\"name\":\"Orthodox Archdiocese of Belgium (Benelux)\",\"description\":\"Exarque des Pays-Bas et du Luxembourg\",\"publisher\":{\"@id\":\"https:\/\/orthodoxia.be\/#organization\"},\"alternateName\":\"IMB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/orthodoxia.be\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/orthodoxia.be\/#organization\",\"name\":\"Orthodox Archdiocese of Belgium (Benelux)\",\"url\":\"https:\/\/orthodoxia.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2024\/02\/cropped-IMB-logo-512-cl-1.png\",\"contentUrl\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2024\/02\/cropped-IMB-logo-512-cl-1.png\",\"width\":512,\"height\":512,\"caption\":\"Orthodox Archdiocese of Belgium (Benelux)\"},\"image\":{\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/orthobel\",\"https:\/\/x.com\/orthobel\",\"https:\/\/www.youtube.com\/c\/orthobel\",\"https:\/\/www.mixcloud.com\/orthobel\/\",\"https:\/\/www.flickr.com\/photos\/148264890@N07\/albums\",\"https:\/\/www.dailymotion.com\/Orthobel\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/person\/36bdc09a0ba8f97671645b7e9d8533ee\",\"name\":\"Georgios Tzatzanis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5e2d1c8037dfa80360af6aee99548eff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5e2d1c8037dfa80360af6aee99548eff?s=96&d=mm&r=g\",\"caption\":\"Georgios Tzatzanis\"},\"sameAs\":[\"http:\/\/orthodoxia.be\"],\"url\":\"https:\/\/orthodoxia.be\/fr\/author\/tzatzanis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles - Archev\u00each\u00e9 Orthodoxe de Belgique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orthodoxia.be\/2018\/10\/10\/\u03ad\u03bd\u03b1\u03c1\u03be\u03b7-\u03c4\u03bf\u03c5-\u03b1\u03ba\u03b1\u03b4\u03b7\u03bc\u03b1\u03ca\u03ba\u03bf\u03cd-\u03ad\u03c4\u03bf\u03c5\u03c2-\u03b9\u03bd\u03c3\u03c4\u03b9\u03c4\u03bf\/","og_locale":"fr_FR","og_type":"article","og_title":"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles - Archev\u00each\u00e9 Orthodoxe de Belgique","og_description":"L\u2019Archev\u00each\u00e9 Orthodoxe de Belgique a proc\u00e9d\u00e9, mercredi 10 octobre 2018, \u00e0 l\u2019ouverture de l\u2019Ann\u00e9e Acad\u00e9mique 2018-2019 de l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles, dans la salle de conf\u00e9rence du Couvent des Dominicains, en plein centre de la ville de Bruxelles. La rencontre d\u00e9buta par une c\u00e9r\u00e9monie &hellip; Continued","og_url":"https:\/\/orthodoxia.be\/2018\/10\/10\/\u03ad\u03bd\u03b1\u03c1\u03be\u03b7-\u03c4\u03bf\u03c5-\u03b1\u03ba\u03b1\u03b4\u03b7\u03bc\u03b1\u03ca\u03ba\u03bf\u03cd-\u03ad\u03c4\u03bf\u03c5\u03c2-\u03b9\u03bd\u03c3\u03c4\u03b9\u03c4\u03bf\/","og_site_name":"Archev\u00each\u00e9 Orthodoxe de Belgique","article_publisher":"https:\/\/www.facebook.com\/orthobel","article_published_time":"2018-10-10T21:35:39+00:00","article_modified_time":"2018-10-18T11:03:17+00:00","og_image":[{"width":1200,"height":549,"url":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg","type":"image\/jpeg"}],"author":"Georgios Tzatzanis","twitter_card":"summary_large_image","twitter_creator":"@orthobel","twitter_site":"@orthobel","twitter_misc":{"\u00c9crit par":"Georgios Tzatzanis","Dur\u00e9e de lecture est.":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#article","isPartOf":{"@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/"},"author":{"name":"Georgios Tzatzanis","@id":"https:\/\/orthodoxia.be\/#\/schema\/person\/36bdc09a0ba8f97671645b7e9d8533ee"},"headline":"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles","datePublished":"2018-10-10T21:35:39+00:00","dateModified":"2018-10-18T11:03:17+00:00","mainEntityOfPage":{"@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/"},"wordCount":744,"publisher":{"@id":"https:\/\/orthodoxia.be\/#organization"},"image":{"@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#primaryimage"},"thumbnailUrl":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg","articleSection":["Actualit\u00e9","Orthodox Logos"],"inLanguage":"fr-BE"},{"@type":"WebPage","@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/","url":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/","name":"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles - Archev\u00each\u00e9 Orthodoxe de Belgique","isPartOf":{"@id":"https:\/\/orthodoxia.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#primaryimage"},"image":{"@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#primaryimage"},"thumbnailUrl":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg","datePublished":"2018-10-10T21:35:39+00:00","dateModified":"2018-10-18T11:03:17+00:00","breadcrumb":{"@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#primaryimage","url":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg","contentUrl":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2018\/10\/IMG_4193-2.jpeg","width":1200,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/orthodoxia.be\/2018\/10\/10\/%ce%ad%ce%bd%ce%b1%cf%81%ce%be%ce%b7-%cf%84%ce%bf%cf%85-%ce%b1%ce%ba%ce%b1%ce%b4%ce%b7%ce%bc%ce%b1%cf%8a%ce%ba%ce%bf%cf%8d-%ce%ad%cf%84%ce%bf%cf%85%cf%82-%ce%b9%ce%bd%cf%83%cf%84%ce%b9%cf%84%ce%bf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orthodoxia.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Ouverture de l\u2019Ann\u00e9e Acad\u00e9mique \u00e0 l\u2019Institut de Th\u00e9ologie Orthodoxe \u00ab\u00a0Ap\u00f4tre Paul\u00a0\u00bb et du Cycle de Conf\u00e9rences \u00ab\u00a0Orthodoxos Logos\u00a0\u00bb \u00e0 Bruxelles"}]},{"@type":"WebSite","@id":"https:\/\/orthodoxia.be\/#website","url":"https:\/\/orthodoxia.be\/","name":"Orthodox Archdiocese of Belgium (Benelux)","description":"Exarque des Pays-Bas et du Luxembourg","publisher":{"@id":"https:\/\/orthodoxia.be\/#organization"},"alternateName":"IMB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orthodoxia.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/orthodoxia.be\/#organization","name":"Orthodox Archdiocese of Belgium (Benelux)","url":"https:\/\/orthodoxia.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/orthodoxia.be\/#\/schema\/logo\/image\/","url":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2024\/02\/cropped-IMB-logo-512-cl-1.png","contentUrl":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2024\/02\/cropped-IMB-logo-512-cl-1.png","width":512,"height":512,"caption":"Orthodox Archdiocese of Belgium (Benelux)"},"image":{"@id":"https:\/\/orthodoxia.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/orthobel","https:\/\/x.com\/orthobel","https:\/\/www.youtube.com\/c\/orthobel","https:\/\/www.mixcloud.com\/orthobel\/","https:\/\/www.flickr.com\/photos\/148264890@N07\/albums","https:\/\/www.dailymotion.com\/Orthobel"]},{"@type":"Person","@id":"https:\/\/orthodoxia.be\/#\/schema\/person\/36bdc09a0ba8f97671645b7e9d8533ee","name":"Georgios Tzatzanis","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/orthodoxia.be\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5e2d1c8037dfa80360af6aee99548eff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e2d1c8037dfa80360af6aee99548eff?s=96&d=mm&r=g","caption":"Georgios Tzatzanis"},"sameAs":["http:\/\/orthodoxia.be"],"url":"https:\/\/orthodoxia.be\/fr\/author\/tzatzanis\/"}]}},"_links":{"self":[{"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/posts\/13222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/comments?post=13222"}],"version-history":[{"count":3,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/posts\/13222\/revisions"}],"predecessor-version":[{"id":13259,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/posts\/13222\/revisions\/13259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/media\/13170"}],"wp:attachment":[{"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/media?parent=13222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/categories?post=13222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/tags?post=13222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}