{"id":69,"date":"2017-09-09T15:39:14","date_gmt":"2017-09-09T15:39:14","guid":{"rendered":"http:\/\/new.orthodoxia.be\/?p=69"},"modified":"2017-10-17T10:20:33","modified_gmt":"2017-10-17T10:20:33","slug":"fete-patronale-du-monastere-de-la-nativite-de-la-mere-de-dieu-a-asten","status":"publish","type":"post","link":"https:\/\/orthodoxia.be\/fr\/2017\/09\/09\/fete-patronale-du-monastere-de-la-nativite-de-la-mere-de-dieu-a-asten\/","title":{"rendered":"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten"},"content":{"rendered":"<p>Le samedi 9 septembre 2017, la Divine Liturgie Pontificale a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e en pr\u00e9sence de nombreux fid\u00e8les et pr\u00eatres pour la f\u00eate de la Nativit\u00e9 de la M\u00e8re de Dieu au Monast\u00e8re d\u2019Asten aux Pays-Bas. De nombreux fid\u00e8les de toute l\u2019Eparchie (dioc\u00e8se) de la Sainte M\u00e9tropole de Belgique et Exarchat des Pays-Bas et du Luxembourg ainsi que des r\u00e9gions avoisinantes d\u2019Allemagne, sont venus participer \u00e0 la f\u00eate patronale du Monast\u00e8re.<\/p>\n<p>C\u2019est dans le recueillement et la simplicit\u00e9 que la Divine Liturgie a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e par Son Eminence le M\u00e9tropolite Ath\u00e9nagoras de Belgique et Exarque des Pays-Bas et du Luxembourg dans l\u2019\u00e9glise du monast\u00e8re remplie de p\u00e8lerins, avec la participation de Son Excellence l\u2018Ev\u00eaque Hilarion d\u2019Edmonton et de pr\u00eatres de la Sainte M\u00e9tropole.<\/p>\n<p>L\u2019hom\u00e9lie a \u00e9t\u00e9 prononc\u00e9e par Son Eminence qui s\u2019est r\u00e9f\u00e9r\u00e9 \u00e0 l\u2019Evangile de la f\u00eate de la Nativit\u00e9 de la M\u00e8re de Dieu. Il dit, entre autres\u00a0: \u00ab\u00a0Voyez, mes tr\u00e8s chers, la vie spirituelle n\u2019est pas une d\u00e9marche ordinaire. Ce n\u2019est pas une partie superficielle de la vie de l\u2019homme. C\u2019est la vie d\u00e9di\u00e9e \u00e0 la recherche du Christ, la vie de l\u2019exp\u00e9rience liturgique, la vie de l\u2019exp\u00e9rience sacramentelle au sein du Corps de l\u2019Eglise. C\u2019est cette vie qu\u2019il faut choisir, pour affermir notre combat spirituel et notre vie eccl\u00e9siale\u00a0\u00bb.<\/p>\n<p>Peu avant la fin de la Divine Liturgie, Son Eminence a proc\u00e9d\u00e9 \u00e0 la b\u00e9n\u00e9diction traditionnelle des pains, puis il remercia tous ceux qui se sont d\u00e9plac\u00e9s jusqu\u2019au monast\u00e8re qui est une oasis spirituelle pleine de la gr\u00e2ce de la Vierge Marie dans le monde moderne.<\/p>\n<p>Par la suite, il remercia Son Excellence l\u2019Ev\u00eaque Hilarion et tous les pr\u00eatres pr\u00e9sents et tout sp\u00e9cialement le R\u00e9v\u00e9rend Archimandrite Sevastianos Latsa, pr\u00eatre de la Sainte M\u00e9tropole d\u2019Allemagne, ainsi que le R\u00e9v\u00e9rend Pr\u00eatre Gabriel Bogdan, pr\u00eatre du Patriarcat de Roumanie en Belgique. Il ne manqua pas de f\u00e9liciter l\u2019Higoum\u00e8ne (Sup\u00e9rieure) du monast\u00e8re, S\u0153ur Ioanna, ainsi que les autres moniales pour leur \u0153uvre importante et m\u00e9ritoire, souhaitant \u00e0 tous d\u2019\u00eatre emplis de la gr\u00e2ce de la Vierge Marie.<\/p>\n<p>Son Eminence a ensuite c\u00e9l\u00e9br\u00e9, en pr\u00e9sence de tous, l\u2019office comm\u00e9moratif pour la bienheureuse d\u00e9funte S\u0153ur Marie. Un r\u00e9ception a \u00e9t\u00e9 offerte \u00e0 tous les p\u00e8lerins.<br \/>\n<a data-flickr-embed=\"true\"  href=\"https:\/\/www.flickr.com\/photos\/148264890@N07\/albums\/72157688335266296\" title=\"Patronal feast of the Orthodox Monastery in Asten (The Netherlands) 9.9.2017\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/farm5.staticflickr.com\/4394\/36996249742_1a5c43ea2f_z.jpg\" width=\"640\" height=\"480\" alt=\"Patronal feast of the Orthodox Monastery in Asten (The Netherlands) 9.9.2017\"><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le samedi 9 septembre 2017, la Divine Liturgie Pontificale a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e en pr\u00e9sence de nombreux fid\u00e8les et pr\u00eatres pour la f\u00eate de la Nativit\u00e9 de la M\u00e8re de Dieu au Monast\u00e8re d\u2019Asten aux Pays-Bas. De nombreux fid\u00e8les de toute l\u2019Eparchie (dioc\u00e8se) de la Sainte M\u00e9tropole de Belgique et Exarchat des Pays-Bas et du Luxembourg &hellip; <a href=\"https:\/\/orthodoxia.be\/fr\/2017\/09\/09\/fete-patronale-du-monastere-de-la-nativite-de-la-mere-de-dieu-a-asten\/\">Continued<\/a><\/p>\n","protected":false},"author":2,"featured_media":62,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-69","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten - Archev\u00each\u00e9 Orthodoxe de Belgique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orthodoxia.be\/2017\/09\/09\/\u03b9\u03b5\u03c1\u03ac-\u03c0\u03b1\u03bd\u03ae\u03b3\u03c5\u03c1\u03b9\u03c2-\u03b9\u03b5\u03c1\u03ac\u03c2-\u03bc\u03bf\u03bd\u03ae\u03c2-\u03b3\u03b5\u03bd\u03b5\u03b8\u03bb\u03af\u03bf\u03c5\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten - Archev\u00each\u00e9 Orthodoxe de Belgique\" \/>\n<meta property=\"og:description\" content=\"Le samedi 9 septembre 2017, la Divine Liturgie Pontificale a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e en pr\u00e9sence de nombreux fid\u00e8les et pr\u00eatres pour la f\u00eate de la Nativit\u00e9 de la M\u00e8re de Dieu au Monast\u00e8re d\u2019Asten aux Pays-Bas. De nombreux fid\u00e8les de toute l\u2019Eparchie (dioc\u00e8se) de la Sainte M\u00e9tropole de Belgique et Exarchat des Pays-Bas et du Luxembourg &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orthodoxia.be\/2017\/09\/09\/\u03b9\u03b5\u03c1\u03ac-\u03c0\u03b1\u03bd\u03ae\u03b3\u03c5\u03c1\u03b9\u03c2-\u03b9\u03b5\u03c1\u03ac\u03c2-\u03bc\u03bf\u03bd\u03ae\u03c2-\u03b3\u03b5\u03bd\u03b5\u03b8\u03bb\u03af\u03bf\u03c5\/\" \/>\n<meta property=\"og:site_name\" content=\"Archev\u00each\u00e9 Orthodoxe de Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/orthobel\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-09T15:39:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-17T10:20:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Georgios Tzatzanis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@orthobel\" \/>\n<meta name=\"twitter:site\" content=\"@orthobel\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Georgios Tzatzanis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/\"},\"author\":{\"name\":\"Georgios Tzatzanis\",\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/person\/36bdc09a0ba8f97671645b7e9d8533ee\"},\"headline\":\"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten\",\"datePublished\":\"2017-09-09T15:39:14+00:00\",\"dateModified\":\"2017-10-17T10:20:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/orthodoxia.be\/#organization\"},\"image\":{\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/\",\"url\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/\",\"name\":\"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten - Archev\u00each\u00e9 Orthodoxe de Belgique\",\"isPartOf\":{\"@id\":\"https:\/\/orthodoxia.be\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg\",\"datePublished\":\"2017-09-09T15:39:14+00:00\",\"dateModified\":\"2017-10-17T10:20:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#primaryimage\",\"url\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg\",\"contentUrl\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/orthodoxia.be\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/orthodoxia.be\/#website\",\"url\":\"https:\/\/orthodoxia.be\/\",\"name\":\"Orthodox Archdiocese of Belgium (Benelux)\",\"description\":\"Exarque des Pays-Bas et du Luxembourg\",\"publisher\":{\"@id\":\"https:\/\/orthodoxia.be\/#organization\"},\"alternateName\":\"IMB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/orthodoxia.be\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/orthodoxia.be\/#organization\",\"name\":\"Orthodox Archdiocese of Belgium (Benelux)\",\"url\":\"https:\/\/orthodoxia.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2024\/02\/cropped-IMB-logo-512-cl-1.png\",\"contentUrl\":\"https:\/\/orthodoxia.be\/wp-content\/uploads\/2024\/02\/cropped-IMB-logo-512-cl-1.png\",\"width\":512,\"height\":512,\"caption\":\"Orthodox Archdiocese of Belgium (Benelux)\"},\"image\":{\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/orthobel\",\"https:\/\/x.com\/orthobel\",\"https:\/\/www.youtube.com\/c\/orthobel\",\"https:\/\/www.mixcloud.com\/orthobel\/\",\"https:\/\/www.flickr.com\/photos\/148264890@N07\/albums\",\"https:\/\/www.dailymotion.com\/Orthobel\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/person\/36bdc09a0ba8f97671645b7e9d8533ee\",\"name\":\"Georgios Tzatzanis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/orthodoxia.be\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5e2d1c8037dfa80360af6aee99548eff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5e2d1c8037dfa80360af6aee99548eff?s=96&d=mm&r=g\",\"caption\":\"Georgios Tzatzanis\"},\"sameAs\":[\"http:\/\/orthodoxia.be\"],\"url\":\"https:\/\/orthodoxia.be\/fr\/author\/tzatzanis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten - Archev\u00each\u00e9 Orthodoxe de Belgique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orthodoxia.be\/2017\/09\/09\/\u03b9\u03b5\u03c1\u03ac-\u03c0\u03b1\u03bd\u03ae\u03b3\u03c5\u03c1\u03b9\u03c2-\u03b9\u03b5\u03c1\u03ac\u03c2-\u03bc\u03bf\u03bd\u03ae\u03c2-\u03b3\u03b5\u03bd\u03b5\u03b8\u03bb\u03af\u03bf\u03c5\/","og_locale":"fr_FR","og_type":"article","og_title":"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten - Archev\u00each\u00e9 Orthodoxe de Belgique","og_description":"Le samedi 9 septembre 2017, la Divine Liturgie Pontificale a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e en pr\u00e9sence de nombreux fid\u00e8les et pr\u00eatres pour la f\u00eate de la Nativit\u00e9 de la M\u00e8re de Dieu au Monast\u00e8re d\u2019Asten aux Pays-Bas. De nombreux fid\u00e8les de toute l\u2019Eparchie (dioc\u00e8se) de la Sainte M\u00e9tropole de Belgique et Exarchat des Pays-Bas et du Luxembourg &hellip; Continued","og_url":"https:\/\/orthodoxia.be\/2017\/09\/09\/\u03b9\u03b5\u03c1\u03ac-\u03c0\u03b1\u03bd\u03ae\u03b3\u03c5\u03c1\u03b9\u03c2-\u03b9\u03b5\u03c1\u03ac\u03c2-\u03bc\u03bf\u03bd\u03ae\u03c2-\u03b3\u03b5\u03bd\u03b5\u03b8\u03bb\u03af\u03bf\u03c5\/","og_site_name":"Archev\u00each\u00e9 Orthodoxe de Belgique","article_publisher":"https:\/\/www.facebook.com\/orthobel","article_published_time":"2017-09-09T15:39:14+00:00","article_modified_time":"2017-10-17T10:20:33+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg","type":"image\/jpeg"}],"author":"Georgios Tzatzanis","twitter_card":"summary_large_image","twitter_creator":"@orthobel","twitter_site":"@orthobel","twitter_misc":{"\u00c9crit par":"Georgios Tzatzanis","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#article","isPartOf":{"@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/"},"author":{"name":"Georgios Tzatzanis","@id":"https:\/\/orthodoxia.be\/#\/schema\/person\/36bdc09a0ba8f97671645b7e9d8533ee"},"headline":"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten","datePublished":"2017-09-09T15:39:14+00:00","dateModified":"2017-10-17T10:20:33+00:00","mainEntityOfPage":{"@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/orthodoxia.be\/#organization"},"image":{"@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#primaryimage"},"thumbnailUrl":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-BE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/","url":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/","name":"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten - Archev\u00each\u00e9 Orthodoxe de Belgique","isPartOf":{"@id":"https:\/\/orthodoxia.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#primaryimage"},"image":{"@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#primaryimage"},"thumbnailUrl":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg","datePublished":"2017-09-09T15:39:14+00:00","dateModified":"2017-10-17T10:20:33+00:00","breadcrumb":{"@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#primaryimage","url":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg","contentUrl":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2017\/09\/c8ab9cbf-a4a2-4d50-86c8-a0257ac89aee.jpg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/orthodoxia.be\/2017\/09\/09\/%ce%b9%ce%b5%cf%81%ce%ac-%cf%80%ce%b1%ce%bd%ce%ae%ce%b3%cf%85%cf%81%ce%b9%cf%82-%ce%b9%ce%b5%cf%81%ce%ac%cf%82-%ce%bc%ce%bf%ce%bd%ce%ae%cf%82-%ce%b3%ce%b5%ce%bd%ce%b5%ce%b8%ce%bb%ce%af%ce%bf%cf%85\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orthodoxia.be\/fr\/"},{"@type":"ListItem","position":2,"name":"F\u00eate patronale du monast\u00e8re de la nativit\u00e9 de la M\u00e9re de Dieu a Asten"}]},{"@type":"WebSite","@id":"https:\/\/orthodoxia.be\/#website","url":"https:\/\/orthodoxia.be\/","name":"Orthodox Archdiocese of Belgium (Benelux)","description":"Exarque des Pays-Bas et du Luxembourg","publisher":{"@id":"https:\/\/orthodoxia.be\/#organization"},"alternateName":"IMB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orthodoxia.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/orthodoxia.be\/#organization","name":"Orthodox Archdiocese of Belgium (Benelux)","url":"https:\/\/orthodoxia.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/orthodoxia.be\/#\/schema\/logo\/image\/","url":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2024\/02\/cropped-IMB-logo-512-cl-1.png","contentUrl":"https:\/\/orthodoxia.be\/wp-content\/uploads\/2024\/02\/cropped-IMB-logo-512-cl-1.png","width":512,"height":512,"caption":"Orthodox Archdiocese of Belgium (Benelux)"},"image":{"@id":"https:\/\/orthodoxia.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/orthobel","https:\/\/x.com\/orthobel","https:\/\/www.youtube.com\/c\/orthobel","https:\/\/www.mixcloud.com\/orthobel\/","https:\/\/www.flickr.com\/photos\/148264890@N07\/albums","https:\/\/www.dailymotion.com\/Orthobel"]},{"@type":"Person","@id":"https:\/\/orthodoxia.be\/#\/schema\/person\/36bdc09a0ba8f97671645b7e9d8533ee","name":"Georgios Tzatzanis","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/orthodoxia.be\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5e2d1c8037dfa80360af6aee99548eff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e2d1c8037dfa80360af6aee99548eff?s=96&d=mm&r=g","caption":"Georgios Tzatzanis"},"sameAs":["http:\/\/orthodoxia.be"],"url":"https:\/\/orthodoxia.be\/fr\/author\/tzatzanis\/"}]}},"_links":{"self":[{"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/posts\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":3,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/posts\/69\/revisions"}],"predecessor-version":[{"id":108,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/posts\/69\/revisions\/108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/media\/62"}],"wp:attachment":[{"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/media?parent=69"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/categories?post=69"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orthodoxia.be\/fr\/wp-json\/wp\/v2\/tags?post=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}